{"id":987,"date":"2012-11-17T08:47:00","date_gmt":"2012-11-17T07:47:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=987"},"modified":"2026-01-19T13:15:02","modified_gmt":"2026-01-19T12:15:02","slug":"zulu-peur-de-rien","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/zulu-peur-de-rien\/","title":{"rendered":"Zulu, peur de rien &#8230;"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Bravo \u00e0 \u00ab\u00a0Zulu\u00a0\u00bb le JPK 1010 de Fran\u00e7ois Alicot pour sa magnifique saison en M\u00e9diterrann\u00e9e<\/h2>\n\n\n\n<p>Fran\u00e7ois et son \u00e9quipage de copains ont toujours \u00e9t\u00e9 \u00e0 l&rsquo;attaque durant cette saison 2012<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>4eme de de la Massila cup de Marseille et de la SNIM<\/li><li>1er au Hyeres s\u00e9ries<\/li><li>2eme de la Giraglia<\/li><li>3eme du Tour de Corse<\/li><li>1er au troph\u00e9e SEMAC<\/li><li>2eme au Championnat MED IRC 4 2012<\/li><\/ul>\n\n\n\n<p>1er du Troph\u00e9e Armen st TropezTr\u00e8s \u00e0 l&rsquo;aise dans la brise soutenue, ils ont termin\u00e9 en beaut\u00e9 en remportant le Troph\u00e9e Semac disput\u00e9 dans du Gros Mistral.<\/p>\n\n\n\n<p>Le magazine Sailing Anarchy ne s&rsquo;y est pas tromp\u00e9 en flashant le Zulu sous spi de capelage dans 40 nds :<\/p>\n\n\n\n<p>\u00ab\u00a0C&rsquo;\u00e9tait le samedi 27 octobre durant le Troph\u00e9e Semac organis\u00e9 par l&rsquo;UNM; la rade de Marseille est en avis de fort coup de vent. Zul\u00f9, le JPK 1010 navigue sous spi lourd dans la premi\u00e8re manche&#8230;. Grosse ambiance c&rsquo;est le jour o\u00f9 le \u00ab\u00a0Napoleon Bonaparte\u00a0\u00bb sombra dans le port de Marseille!! Thanks to Anarchist Francois.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bravo \u00e0 \u00ab\u00a0Zulu\u00a0\u00bb le JPK 1010 de Fran\u00e7ois Alicot pour sa magnifique saison en M\u00e9diterrann\u00e9e Fran\u00e7ois et son \u00e9quipage de copains ont toujours \u00e9t\u00e9 \u00e0 l&rsquo;attaque durant cette saison 2012 4eme de de la Massila cup de Marseille et de la SNIM 1er au Hyeres s\u00e9ries 2eme de la Giraglia 3eme du Tour de Corse [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":988,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[51,76,80,5,40,71,79],"modele":[141],"class_list":["post-987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-course","tag-coupe-de-france-irc","tag-giraglia","tag-hyeres-series","tag-5","tag-snim","tag-tour-de-corse-a-la-voile","tag-trophee-semac","modele-jpk-1010"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zulu, peur de rien ... &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/zulu-peur-de-rien\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zulu, peur de rien ... &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"Bravo \u00e0 \u00ab\u00a0Zulu\u00a0\u00bb le JPK 1010 de Fran\u00e7ois Alicot pour sa magnifique saison en M\u00e9diterrann\u00e9e Fran\u00e7ois et son \u00e9quipage de copains ont toujours \u00e9t\u00e9 \u00e0 l&rsquo;attaque durant cette saison 2012 4eme de de la Massila cup de Marseille et de la SNIM 1er au Hyeres s\u00e9ries 2eme de la Giraglia 3eme du Tour de Corse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/zulu-peur-de-rien\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-17T07:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"Zulu, peur de rien &#8230;\",\"datePublished\":\"2012-11-17T07:47:00+00:00\",\"dateModified\":\"2026-01-19T12:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/\"},\"wordCount\":179,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/all_french.jpg_sml.jpg\",\"keywords\":[\"Coupe de France IRC\",\"Giraglia\",\"Hy\u00e8res S\u00e9ries\",\"JPK 1010\",\"SNIM\",\"Tour de Corse \u00e0 la voile\",\"Troph\u00e9e SEMAC\"],\"articleSection\":[\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/\",\"name\":\"Zulu, peur de rien ... &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/all_french.jpg_sml.jpg\",\"datePublished\":\"2012-11-17T07:47:00+00:00\",\"dateModified\":\"2026-01-19T12:15:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/all_french.jpg_sml.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/all_french.jpg_sml.jpg\",\"width\":550,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/zulu-peur-de-rien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/course\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zulu, peur de rien &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zulu, peur de rien ... &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/zulu-peur-de-rien\/","og_locale":"en_GB","og_type":"article","og_title":"Zulu, peur de rien ... &#8212; JPK Composites","og_description":"Bravo \u00e0 \u00ab\u00a0Zulu\u00a0\u00bb le JPK 1010 de Fran\u00e7ois Alicot pour sa magnifique saison en M\u00e9diterrann\u00e9e Fran\u00e7ois et son \u00e9quipage de copains ont toujours \u00e9t\u00e9 \u00e0 l&rsquo;attaque durant cette saison 2012 4eme de de la Massila cup de Marseille et de la SNIM 1er au Hyeres s\u00e9ries 2eme de la Giraglia 3eme du Tour de Corse [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/course\/zulu-peur-de-rien\/","og_site_name":"JPK Composites","article_published_time":"2012-11-17T07:47:00+00:00","article_modified_time":"2026-01-19T12:15:02+00:00","og_image":[{"width":550,"height":337,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg","type":"image\/jpeg"}],"author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"Zulu, peur de rien &#8230;","datePublished":"2012-11-17T07:47:00+00:00","dateModified":"2026-01-19T12:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/"},"wordCount":179,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg","keywords":["Coupe de France IRC","Giraglia","Hy\u00e8res S\u00e9ries","JPK 1010","SNIM","Tour de Corse \u00e0 la voile","Troph\u00e9e SEMAC"],"articleSection":["Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/","url":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/","name":"Zulu, peur de rien ... &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg","datePublished":"2012-11-17T07:47:00+00:00","dateModified":"2026-01-19T12:15:02+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/all_french.jpg_sml.jpg","width":550,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/zulu-peur-de-rien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.jpk.fr\/category\/course\/"},{"@type":"ListItem","position":3,"name":"Zulu, peur de rien &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/987\/revisions"}],"predecessor-version":[{"id":16009,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/987\/revisions\/16009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/988"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=987"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}