{"id":968,"date":"2013-04-02T08:07:00","date_gmt":"2013-04-02T06:07:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=968"},"modified":"2026-01-19T13:15:01","modified_gmt":"2026-01-19T12:15:01","slug":"debut-de-saison-2013-exceptionnel-pour-le-jpk-1010","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/","title":{"rendered":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010"},"content":{"rendered":"<h2 class=\"wp-block-heading\">SPI, SNIM, RORC Easter Challenge<\/h2>\n\n\n\n<p>1er Spi Ouest France \u00ab\u00a0L\u00e9on\u00a0\u00bb du chantier JPK<br>1er SNIM \u00ab\u00a0Zulu\u00a0\u00bbde Fran\u00e7ois Alicot<br>1er RORC Easter challenge (UK) \u00ab\u00a0Strait Dealer\u00a0\u00bb de David Franks<\/p>\n\n\n\n<p>SNIM<br>Bravo \u00e0 Fran\u00e7ois Alicot et toute son \u00e9quipe pur cette belle et nette victoire. Apr\u00e8s une ann\u00e9e de prise en main de \u00ab\u00a0Zulu\u00a0\u00bb son JPK 1010 et des r\u00e9sultats d\u00e9j\u00e0 excellents en 2012, Fran\u00e7ois d\u00e9marre&nbsp; sa saison 2013 en fanfare.<\/p>\n\n\n\n<p>RORC Easter Challenge<br>7 manches gagn\u00e9es sur 7 courues, \u00ab\u00a0Strait Dealer\u00a0\u00bb le 1010 de David Franks men\u00e9 par Graham Sunderland et une \u00e9quipe de champions n&rsquo;a pas fait de d\u00e9tail sur sa 1\u00e8re course de saison.<br>La concurrence est pr\u00e9venue, \u00ab\u00a0Strait Dealer\u00a0\u00bb va vite, tr\u00e8s vite et son app\u00e9tit de victoire f\u00e9roce&#8230;<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/easter.pdf\" type=\"application\/pdf\" style=\"width:100%;height:270px\" aria-label=\"Embed of Contenu embarqu\u00e9 RORC Easter Challenge IRC3..\"><\/object><a href=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/easter.pdf\">RORC Easter Challenge IRC3<\/a><a href=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/easter.pdf\" class=\"wp-block-file__button\" download>T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/ech13d1-741.jpg\" alt=\"\" data-id=\"970\" data-full-url=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/ech13d1-741.jpg\" data-link=\"https:\/\/www.jpk.fr\/?attachment_id=970\" class=\"wp-image-970\" srcset=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/ech13d1-741.jpg 640w, https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/ech13d1-741-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"blocks-gallery-item__caption\">Strait Dealer,JPK 1010,GBR 1250<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/813.jpeg\" alt=\"\" data-id=\"971\" data-full-url=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/813.jpeg\" data-link=\"https:\/\/www.jpk.fr\/?attachment_id=971\" class=\"wp-image-971\" srcset=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/813.jpeg 600w, https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/813-300x200.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"640\" height=\"426\" src=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-rec-strait-dealer-jpk-1010-david-franks-pw.jpg\" alt=\"\" data-id=\"972\" data-full-url=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-rec-strait-dealer-jpk-1010-david-franks-pw.jpg\" data-link=\"https:\/\/www.jpk.fr\/?attachment_id=972\" class=\"wp-image-972\" srcset=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-rec-strait-dealer-jpk-1010-david-franks-pw.jpg 640w, https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-rec-strait-dealer-jpk-1010-david-franks-pw-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"blocks-gallery-item__caption\">Strait Dealer,GBR 1250,<\/figcaption><\/figure><\/li><\/ul><\/figure>","protected":false},"excerpt":{"rendered":"<p>SPI, SNIM, RORC Easter Challenge 1er Spi Ouest France \u00ab\u00a0L\u00e9on\u00a0\u00bb du chantier JPK1er SNIM \u00ab\u00a0Zulu\u00a0\u00bbde Fran\u00e7ois Alicot1er RORC Easter challenge (UK) \u00ab\u00a0Strait Dealer\u00a0\u00bb de David Franks SNIMBravo \u00e0 Fran\u00e7ois Alicot et toute son \u00e9quipe pur cette belle et nette victoire. Apr\u00e8s une ann\u00e9e de prise en main de \u00ab\u00a0Zulu\u00a0\u00bb son JPK 1010 et des r\u00e9sultats [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":973,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[5,61,40,48],"modele":[141],"class_list":["post-968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-course","tag-5","tag-rorc-easter-challenge","tag-snim","tag-spi-ouest-france","modele-jpk-1010"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"SPI, SNIM, RORC Easter Challenge 1er Spi Ouest France \u00ab\u00a0L\u00e9on\u00a0\u00bb du chantier JPK1er SNIM \u00ab\u00a0Zulu\u00a0\u00bbde Fran\u00e7ois Alicot1er RORC Easter challenge (UK) \u00ab\u00a0Strait Dealer\u00a0\u00bb de David Franks SNIMBravo \u00e0 Fran\u00e7ois Alicot et toute son \u00e9quipe pur cette belle et nette victoire. Apr\u00e8s une ann\u00e9e de prise en main de \u00ab\u00a0Zulu\u00a0\u00bb son JPK 1010 et des r\u00e9sultats [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-02T06:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:15:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"532\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010\",\"datePublished\":\"2013-04-02T06:07:00+00:00\",\"dateModified\":\"2026-01-19T12:15:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1545302_515180285159976_163866393_n.jpg\",\"keywords\":[\"JPK 1010\",\"RORC Easter Challenge\",\"SNIM\",\"Spi Ouest France\"],\"articleSection\":[\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/\",\"name\":\"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1545302_515180285159976_163866393_n.jpg\",\"datePublished\":\"2013-04-02T06:07:00+00:00\",\"dateModified\":\"2026-01-19T12:15:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1545302_515180285159976_163866393_n.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/1545302_515180285159976_163866393_n.jpg\",\"width\":800,\"height\":532},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/course\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/","og_locale":"en_GB","og_type":"article","og_title":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites","og_description":"SPI, SNIM, RORC Easter Challenge 1er Spi Ouest France \u00ab\u00a0L\u00e9on\u00a0\u00bb du chantier JPK1er SNIM \u00ab\u00a0Zulu\u00a0\u00bbde Fran\u00e7ois Alicot1er RORC Easter challenge (UK) \u00ab\u00a0Strait Dealer\u00a0\u00bb de David Franks SNIMBravo \u00e0 Fran\u00e7ois Alicot et toute son \u00e9quipe pur cette belle et nette victoire. Apr\u00e8s une ann\u00e9e de prise en main de \u00ab\u00a0Zulu\u00a0\u00bb son JPK 1010 et des r\u00e9sultats [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/","og_site_name":"JPK Composites","article_published_time":"2013-04-02T06:07:00+00:00","article_modified_time":"2026-01-19T12:15:01+00:00","og_image":[{"width":800,"height":532,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg","type":"image\/jpeg"}],"author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010","datePublished":"2013-04-02T06:07:00+00:00","dateModified":"2026-01-19T12:15:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/"},"wordCount":153,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg","keywords":["JPK 1010","RORC Easter Challenge","SNIM","Spi Ouest France"],"articleSection":["Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/","url":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/","name":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010 &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg","datePublished":"2013-04-02T06:07:00+00:00","dateModified":"2026-01-19T12:15:01+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/1545302_515180285159976_163866393_n.jpg","width":800,"height":532},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/debut-de-saison-2013-exceptionnel-pour-le-jpk-1010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.jpk.fr\/category\/course\/"},{"@type":"ListItem","position":3,"name":"D\u00e9but de saison 2013 exceptionnel pour le JPK 1010"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=968"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/968\/revisions"}],"predecessor-version":[{"id":16006,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/968\/revisions\/16006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/973"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=968"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}