{"id":932,"date":"2013-08-30T15:44:00","date_gmt":"2013-08-30T13:44:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=932"},"modified":"2026-01-19T15:21:00","modified_gmt":"2026-01-19T14:21:00","slug":"rolex-fastnet-race-2013","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/rolex-fastnet-race-2013\/","title":{"rendered":"Rolex Fastnet Race 2013"},"content":{"rendered":"<h2 class=\"wp-block-heading\">R\u00e9cit d&rsquo;une victoire par Pascal LOISON<\/h2>\r\n\r\n\r\n\r\n<p>D\u00e9part dimanche 11 ao\u00fbt, devant le Royal Squadron, \u00e0 Cowes ; c&rsquo;est le jour de l&rsquo;anniversaire d&rsquo;Alexis. Je lui demande ce qu&rsquo;il veut comme cadeau d&rsquo;anniversaire, nous convenons qu&rsquo;une Rolex, prix r\u00e9serv\u00e9 au vainqueur toutes classes, ce serait pas mal !<\/p>\r\n\r\n\r\n<figure class=\"wp-block-post-featured-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"320\" height=\"480\" src=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg 320w, https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller-200x300.jpeg 200w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/figure>\r\n\r\n\r\n<p>M\u00eame si nous en parlons, l&rsquo;objectif affich\u00e9 ce n&rsquo;est pas la victoire toutes classes, c&rsquo;est de gagner en double, voire en IRC3 puisque depuis le d\u00e9but de la pr\u00e9paration \u00e0 ce Fastnet nous avons \u00e0 chaque fois fait le doubl\u00e9, que ce soit avec \u00ab\u00a0L\u00e9on\u00a0\u00bb sur Cowes Cherbourg&nbsp; en septembre 2012 ou avec \u00ab\u00a0Night and Day\u00a0\u00bb cette ann\u00e9e sur Cowes Dieppe, puis Cowes Dinard;&nbsp; mais c&rsquo;est vrai que la victoire toutes classes d&rsquo;Alexis associ\u00e9 pour l&rsquo;occasion \u00e0 un autre figariste Joan Ahrweiller \u00e0 la Channel Race a montr\u00e9 que c&rsquo;\u00e9tait possible, alors pourquoi pas r\u00eaver un peu ?<\/p>\r\n\r\n\r\n\r\n<p>La m\u00e9t\u00e9o nous va bien, pas de gros temps annonc\u00e9 sur toute la course,&nbsp; pour nous du&nbsp; louvoyage pendant deux jours, puis du reaching dans le m\u00e9dium, apr\u00e8s on ne sait pas, c&rsquo;est trop loin, \u00e7a va changer ; il semble que les gros ratings ( il y a des bestiaux de 100 pieds avec des ratings IRC sup\u00e9rieurs \u00e0 1,800 , des volvo 70 qui semblent d\u00e9j\u00e0 plus petits, plein de superbes b\u00e9canes qui vont aller beaucoup plus vite que nous) ne vont faire que du louvoyage, puis du vent arri\u00e8re, donc pour une fois ils ne vont pas forc\u00e9ment \u00eatre avantag\u00e9s; les petits bateaux ont leur chance, \u00e0 nous de l&rsquo;utiliser au mieux;<br>parmi ces petits bateaux il en faut des polyvalents, car il y aura du reaching; ce n&rsquo;est pas forc\u00e9ment la tasse de th\u00e9 des tout petits ratings comme \u00ab\u00a0Iromiguy\u00a0\u00bb,&nbsp; Nicholson 33 vainqueur toutes classes en 2005, ou les comtessa 32 ou sigmas 33; bref&nbsp; les JPK 1010, bien polyvalents, peuvent tirer leur \u00e9pingle du jeu. Reste que dans tous les ratings moyens comme le n\u00f4tre, et en particulier dans les JPK 1010 il y a du beau monde,&nbsp; \u00ab\u00a0Foggy Dew\u00a0\u00bb&nbsp; vainqueur de la pr\u00e9c\u00e9dente \u00e9dition dans sa classe faisant un peu figure d&rsquo;\u00e9pouvantail; en plus il n&rsquo;est pas facile \u00e0 contr\u00f4ler car il est en classe IRC4 avec un rating de 1,006, alors que notre rating de 1,009 nous place en classe IRC 3, et que notre d\u00e9part est d\u00e9cal\u00e9 de 20 minutes apr\u00e8s le sien;<br>En attendant le d\u00e9part, on regarde, le spectacle est superbe,&nbsp; le thermique de SW est en train de s&rsquo;\u00e9tablir, les grands multicoques dont Spibndrift et Banque Pop partent en premier, la vitesse avec laquelle ils&nbsp; traversent le Solent&nbsp; en tirant des bords&nbsp; est hallucinante; puis viennent les Imoca, les 40 pieds, et enfin le d\u00e9part des IRC4&nbsp; 20 minutes avant nous; le courant est encore contraire, presque tout le monde part c\u00f4t\u00e9 \u00ab&nbsp; continent&nbsp;\u00bb, Iromiguy est un peu seul c\u00f4t\u00e9 \u00eele de Wight, il nous semble qu&rsquo;il ne s&rsquo;en tire pas trop mal, et que \u00e7a devrait \u00eatre encore plus net quand ce sera notre tour avec la renverse qui se fait plus t\u00f4t c\u00f4t\u00e9 \u00eele; \u00ab\u00a0Foggy Dew\u00a0\u00bb est c\u00f4t\u00e9 continent et comme d&rsquo;habitude \u00e7a ne semble pas se passer trop mal pour lui ! Bref nous sommes d&rsquo;accord, on partira c\u00f4t\u00e9 \u00eele, pour b\u00e9n\u00e9ficier de la renverse plus pr\u00e9coce et des \u00ab&nbsp;gauches&nbsp;\u00bb qui d\u00e9bouchent des vall\u00e9es par SW; on sera plus maniables que les grosses b\u00e9canes qui partent apr\u00e8s nous et on devrait pouvoir en gardant le c\u00f4t\u00e9 \u00eele s&rsquo;abriter des d\u00e9vents;<br>D\u00e9part; on est un peu seuls c\u00f4t\u00e9 \u00eele; \u00ab\u00a0Raging Bee\u00a0\u00bb l&rsquo;autre 1010 cherbourgeois, en double \u00e9galement, est avec nous, \u00e7a nous donne un bon li\u00e8vre, les croisements sont chauds au d\u00e9part, tribord je passe, babord, je te laisse passer, on finit par prendre un petit avantage, c&rsquo;est mieux comme \u00e7a car 608 milles au contact \u00e7a promettait d&rsquo;\u00eatre difficile !<br>Sortie du Solent, comme souvent toutes les classes IRC se retrouvent l\u00e0, les petits partis devant, les gros partis derri\u00e8re , le Solent semble un peu petit!&nbsp; Esimit Europa ( 100 pieds \u00e0 quille basculante) passe \u00e0 10 m\u00e8tres; il doit \u00eatre \u00e0 onze noeuds ouaouhhh , il est sous notre vent, \u00e7a a pas l&rsquo;air de le g\u00eaner beaucoup ! \u00ab\u00a0Raging Bee\u00a0\u00bb longe les Shingles, \u00e7a n&rsquo;avait pas march\u00e9 du tout \u00e0 Cowes Dinard, aujourd&rsquo;hui \u00e7a marche ( comprenne qui pourra) et ils repassent devant ( Grrrr \u2026..); on est donc toujours au contact du li\u00e8vre mais il court devant \u2026.<br>Louvoyage entre les Needles et Saint Alban; le courant nous aide; objectif Portland; c&rsquo;est le premier passage \u00e0 niveau; les gros vont passer sans probl\u00e8me, pour nous, c&rsquo;est moins certain, ce sera la renverse , probablement la mort du thermique, on esp\u00e8re que le synoptique de NW sera bien l\u00e0. On repasse \u00ab\u00a0Raging Bee\u00a0\u00bb sur une petite bascule;<br>Portland: c&rsquo;est toujours un moment cl\u00e9; \u00e7a mollit; nous croisons \u00ab\u00a0Swinhoe\u00a0\u00bb de Philippe Vicariot; on va bien en vitesse pure, plusieurs options se dessinent, l&rsquo;AIS permet une analyse plus fine de ce qui se passe dans les diff\u00e9rents paquets de bateaux;<br>&nbsp;&nbsp;&nbsp; \u2043&nbsp;&nbsp;&nbsp; tout \u00e0 la c\u00f4te, babord amures, pour s&rsquo;abriter du courant contraire \u00e9tabli maintenant \u00e0 cet endroit; \u00e7a n&rsquo;a pas l&rsquo;air mauvais au d\u00e9but mais \u00e7a freine fort quand ils approchent de l&rsquo;extr\u00e9mit\u00e9 de la pointe; passera ? Passera pas ?<br>&nbsp;&nbsp;&nbsp; \u2043&nbsp;&nbsp;&nbsp; au large,&nbsp; tribord amures, c&rsquo;est plus logique, le courant est plus faible et va se renverser plus tard, par contre le vent semble bien mou, le cap peu rapprochant;<br>&nbsp;&nbsp;&nbsp; \u2043&nbsp;&nbsp;&nbsp; entre les 2,&nbsp; c&rsquo;est nous, au large au d\u00e9but&nbsp; tribord amures pour avoir une renverse plus tardive, babord amures ensuite cap \u00e0 l&rsquo;ouest&nbsp; pour \u00eatre appuy\u00e9s par le contre -jus qui sort de la baie de Lyme et prend une orientation Nord-sud au contact du Bill of Portland; et l\u00e0 miracle, une fois l&rsquo;aplomb de la pointe de Portland pass\u00e9, c&rsquo;est une fronti\u00e8re m\u00e9t\u00e9o, de l&rsquo;autre c\u00f4t\u00e9 on tombe dans le Nord ouest esp\u00e9r\u00e9 on repart tribord amures cap direct vers Star Point; \u00e0 quelques dizaines de m\u00e8tres pr\u00e8s, \u00e7a passe ou \u00e7a passe pas, les \u00e9carts sont \u00e9normes, ceux qui sont rest\u00e9s \u00e0 l&rsquo;est de la pointe vont mettre un paquet de temps \u00e0 toucher le nouveau vent et \u00e0 repartir; o\u00f9 est \u00ab\u00a0Foggy Dew\u00a0\u00bb ? Myst\u00e8re, il \u00e9tait devant, mais plus \u00e0 terre la derni\u00e8re fois qu&rsquo;on l&rsquo;a localis\u00e9 \u00e0 l&rsquo;AIS, l&rsquo;avenir montrera que \u00e7a s&rsquo;\u00e9tait bien pass\u00e9 pour lui aussi ! Quant \u00e0 \u00ab\u00a0Raging Bee\u00a0\u00bb on ne le reverra plus;<\/p>\r\n\r\n\r\n\r\n<p>Apr\u00e8s le vent reste nord ouest, promis comme adonnant progressivement; on est au pr\u00e8s tribord amures, un peu sous la route, \u00e7a va s&rsquo;arranger, \u00e9loignons nous de Portland et des copains qui y sont encore ! On ne rentre surtout pas dans les baies,&nbsp; on fait en gros la route directe vers Lands end compte tenu de l&rsquo;adonnante \u00e0 venir; il fait beau, c&rsquo;est du pr\u00e8s \u00ab&nbsp; humain&nbsp;\u00bb, il ne fait m\u00eame pas froid;<\/p>\r\n\r\n\r\n\r\n<p>A partir de Lands End, la question essentielle est le choix du parcours; on peut passer o\u00f9 on veut par rapport aux Scilly, au nord, au sud, voire dedans, mais il y a trois DST \u00e0 respecter, qui sont des zones de navigation interdites;<br>\u00a0\u00a0\u00a0 &#8211; celui de Longships est consid\u00e9rablement \u00e9tendu vers le nord, le contourner par l&rsquo;est semble donc risqu\u00e9; c&rsquo;est tentant au d\u00e9part car on est dans une logique de pr\u00e8s serr\u00e9 depuis le d\u00e9part et dans cette route on continue \u00e0 faire du pr\u00e8s; et les cartes y montrent plus de pression; c&rsquo;est la logique de contournement par l&rsquo;est de la pointe de la dorsale, pour garder du vent; mais quand le SW esp\u00e9r\u00e9 va s&rsquo;\u00e9tablir, il va forc\u00e9ment arriver de l&rsquo;ouest; combien de temps avant ? Pourra t on faire route directe sur le Fastnet ? A quelle vitesse ? Le gain esp\u00e9r\u00e9 est faible, le risque \u00e9lev\u00e9<br>\u00a0\u00a0\u00a0 \u2043\u00a0\u00a0\u00a0 Avant le d\u00e9part de Cowes, les routages nous faisaient passer sous les Scilly, au bon plein, cap \u00e0 l&rsquo;ouest pour aller le plus \u00e0 l&rsquo;ouest possible chercher cette bascule;<br>\u00a0\u00a0\u00a0 \u2043\u00a0\u00a0\u00a0 mais nous sommes en avance sur notre routage ( c&rsquo;est un \u00ab\u00a0 d\u00e9faut\u00a0\u00bb du JPK 1010, \u00e7a nous arrive souvent), le timing annonc\u00e9 de la bascule nous incite maintenant \u00e0 passer \u00e0 l&rsquo;est puis au nord de l&rsquo;archipel des Scilly; il faut au d\u00e9part se faire un peu violence pour d\u00e9brider les \u00e9coutes et passer sous le DST , par contre on ne va pas le faire longtemps, rapidement\u00a0 on refera du pr\u00e8s pour contourner les Scilly par le Nord en gagnant sur la route ; on ne sera pas trop dans l&rsquo;est pour \u00eatre certain d&rsquo;avoir une allure rapide une fois le SW install\u00e9; on sera certain de faire la route directe vers le caillou et donc de gagner du temps par rapport \u00e0 ceux qui vont aller plus dans l&rsquo;ouest en passant sous les Scilly; enfin \u00e0 court terme il y a une belle \u00ab\u00a0 gauche \u00ab\u00a0 \u00e0 prendre \u00e0 l&rsquo;est des Scilly;<br>la remont\u00e9e de la mer d&rsquo;Irlande se passe bien; c&rsquo;est du pr\u00e8s dans un vent de plus en plus l\u00e9ger, on joue bien quelques bascules qui nous permettent de rester au contact de quelques figaro et autres bateaux th\u00e9oriquement plus rapides; Warhorse, IMX 40 en double va bien et nous prend peu \u00e0 peu 5 milles d&rsquo;avance, il nous inqui\u00e8te un peu celui l\u00e0 ! Et puis vient le moment du virement; on passe enfin babord amures, cap au 350, et \u00e7a va adonner nous permettant de faire la route vers le coin NE du DST Fastnet; le front chaud arrive, et avec lui le SW attendu et du temps irlandais; il pleut, on envoie l&rsquo;asym\u00e9trique et \u00e7a va bien ! Par rapport \u00e0 ceux qui \u00e9taient pass\u00e9s \u00e0 l&rsquo;est du DST Longships ( dont Alka\u00efd),\u00a0 on est mieux car eux ne sont pas \u00e0 une allure\u00a0 spiable; par rapport \u00e0 ceux qui ont plus investi dans l&rsquo;ouest, ils peuvent certes spier plus confortablement, voire viser directement le caillou en passant \u00e0 l&rsquo;ouest du DST Fastnet mais ils ont beaucoup rallong\u00e9 la route et peut \u00eatre un peu trop; on l&rsquo;esp\u00e8re en tout cas et on g\u00e8re au mieux le bateau dans le vent bien soutenu et humide qui nous catapulte vers l&rsquo;Irlande ( 25 noeuds de SW,\u00a0 crachin); \u00e7a force et \u00e7a refuse un peu, on est \u00e0 nouveau sous g\u00e9nois, plut\u00f4t contents pour ceux qui sont dans notre est et qui vont ralentir beaucoup. On arrive au WP virtuel du coin NE du DST Fastnet<br>Le contournement du DST Fastnet est le moment o\u00f9 on se dit qu&rsquo;il se passe quelque chose; c&rsquo;est souvent comme \u00e7a dans les courses qu&rsquo;on gagne, il y a des enchainements heureux, des passages o\u00f9 on se sent en phase avec les \u00e9l\u00e9ments; il fait nuit, on fait du pr\u00e8s babord amures dans du vent bien sud qui nous permet de faire route directe vers le caillou; on retrouve \u00ab\u00a0Foggy Dew\u00a0\u00bb \u00e0 l&rsquo;AIS; ils \u00e9taient donc bien toujours devant! On les esp\u00e9rait avec \u00ab\u00a0Alka\u00efd\u00a0\u00bb&#8230;..Grimaces&#8230;.Oui, mais ils vont prendre la \u00ab\u00a0droite\u00a0\u00bb annonc\u00e9e plus tard pendant le louvoyage vers la bou\u00e9e de d\u00e9gagement Pantaneius. Du coup on va se refaire un peu car nous on va \u00eatre plus proches du timing id\u00e9al avec du vent bien sud pour aller au caillou et\u00a0 qui va prendre de la droite tr\u00e8s vite d\u00e8s qu&rsquo;on l&rsquo;aura pass\u00e9.<br>Le passage du phare est un moment magique; on est \u00e0 500 m\u00e8tres, on ne le voit pas !\u00a0 WP virtuel lui aussi ? La t\u00eate de m\u00e2t est dans un brouillard opaque, il bruine, il y a des bateaux partout mais on les voit au dernier moment, dans ces passages l\u00e0 l&rsquo;AIS c&rsquo;est bien car ceux qui ont contourn\u00e9 le DST par l&rsquo;ouest arrivent sous spi pleine balle pendant que les autres arrivent au pr\u00e8s. On continue babord amures une dizaine de minutes le temps d&rsquo;envoyer au RORC le texto donnant\u00a0 notre temps de passage( 00H 00 minutes et quelques secondes, \u00e7a ne s&rsquo;invente pas), puis on vire et l&rsquo;adonnante qui suit va nous permettre de faire une lay line parfaite de 6 milles sur Pantaneius Buoy.. On en profite pour faire le point sur le classement au caillou; on est super bien, tout reste possible m\u00eame si Foggy Dew, 2eme overall au caillou\u00a0 est un peu devant; bient\u00f4t du reaching, il n&rsquo; a qu&rsquo;un safran, on va voir ce qu&rsquo;on va voir!<br>\u00a0Cap sur les Scilly ! Le vent est encore assez fort, l&rsquo;allure assez serr\u00e9e, les fichiers laissent \u00e0 penser que dans une dizaine d&rsquo;heures \u00e7a va refuser \u00e0 nouveau; on renvoie donc l&rsquo;asym\u00e9trique magique et on r\u00e9siste \u00e0 l&rsquo;envie de faire de longs surfs, on cape un peu plus que la route, ce sera bon pour la suite; Foggy Dew cape un peu moins, \u00e7a nous conforte dans l&rsquo;option, si on les suit \u00e7a va \u00eatre compliqu\u00e9 de les doubler; le temps s&rsquo;am\u00e9liore, il ne pleut plus, le clapot n&rsquo;est pas trop m\u00e9chant, \u00e7a va vite, c&rsquo;est rigolo l&rsquo;asym\u00e9trique c&rsquo;est une allure tr\u00e8s r\u00e9guli\u00e8re: peu d&rsquo;acc\u00e9l\u00e9rations foudroyantes, de surfs d\u00e9ments \u00e0 raconter au bar,\u00a0 c&rsquo;est pas la conduite grand prix, mais une vitesse \u00e9lev\u00e9e, constante, c&rsquo;est un peu le TGV; quand on part au tas ( ben oui \u00e7a arrive), c&rsquo;est pas cher; l\u00e0 o\u00f9 avec un sym\u00e9trique on s&rsquo;arr\u00eate avant de remettre le camion sur la route, l\u00e0 on passe de neuf \u00e0 huit noeuds, et \u00e7a repart quasiment sans toucher \u00e0 l&rsquo;\u00e9coute. \u00ab\u00a0Foggy Dew\u00a0\u00bb est maintenant visible, il tombe sous la route, on reste un peu au dessus, on s&rsquo;accroche;\u00a0 un peu plus tard ils remettent un g\u00e9nois, puis probablement un code z\u00e9ro; nous on change rien, on continue sur la tranche, \u00e0 chaque sieste, celui qui se r\u00e9veille et qui n&rsquo;a pas regard\u00e9 depuis une demi heure le plan d&rsquo;eau confirme, ils doivent moins bien dormir sur \u00ab\u00a0Foggy Dew\u00a0\u00bb car le rel\u00e8vement \u00e9volue dans le bon sens pour nous.<br>Aux Scilly, la donne a chang\u00e9; c&rsquo;est nous qui sommes devant, deux petits milles, mais le parcours nous avantage plut\u00f4t; c&rsquo;est du vrai portant, sous grand spi, c&rsquo;est maniable, on est plus l\u00e9gers, \u00e7a va \u00eatre compliqu\u00e9 pour eux! Il y a plein de bonnes nouvelles;\u00a0 d&rsquo;abord quand on regarde vers le nord, il y a un groupe de bateaux qui arrive sous g\u00e9nois en longeant Bishop Rock; ce sont ceux qui ont surf\u00e9 les vagues dans le bord pr\u00e9c\u00e9dent et sont donc pass\u00e9s au dessus du DST ouest Scilly; parmi eux l&rsquo;A 35 \u00ab\u00a0Prime Time\u00a0\u00bb qui \u00e9tait devant au caillou et qu&rsquo;on aime bien mieux voir derri\u00e8re; et puis la f\u00e9e Internet\u00a0 nous confirme qu&rsquo;on est super bien au classement overall; la seule ombre au tableau est un certain MC 34 \u00ab\u00a0Patton\u00a0\u00bb avec Gery Trenteseaux; il est loin devant en temps r\u00e9el, mais si le vent s&rsquo;essouffle \u00e0 la fin\u00a0 ( un classique en baie de Plymouth) il peut tirer son \u00e9pingle du jeu;<br>La derni\u00e8re nuit semble bien longue; pass\u00e9 le Lizard il reste encore 40 milles! Une \u00e9ternit\u00e9 \u2026. On empanne \u00e0 la bascule, mais surtout \u2026..\u00e0 l&rsquo;AIS, seule fa\u00e7on de contr\u00f4ler \u00ab\u00a0Foggy Dew\u00a0\u00bb; on a notre plan en baie de Plymouth pour chasser le MC 34, utiliser au mieux la fin du courant montant et le vent; mais on surveille les r\u00e9troviseurs et quand \u00ab\u00a0Foggy Dew\u00a0\u00bb tente d&rsquo;aller \u00e0 la c\u00f4te un peu vite \u00e0 notre go\u00fbt on va avec lui ! Ce serait trop dommage qu&rsquo;ils trouvent quelque chose et pas nous&#8230;&#8230; Gery\u00a0 Trenteseaux a pass\u00e9 la ligne, c&rsquo;est jouable.<br>L&rsquo;arriv\u00e9e est particuli\u00e8re; \u00e0 quinze minutes de la ligne un front arrive et une pluie diluvienne nous tombe dessus; on n&rsquo;y voit rien; une pens\u00e9e \u00e9mue pour les cam\u00e9ras qui\u00a0 font des images et vont essayer de donner une id\u00e9e \u00ab\u00a0 sea sex and sun\u00a0\u00bb de cette Rolex Fastnet Race avec ces images \u2026. Pas de doute, metteur en sc\u00e8ne, c&rsquo;est un m\u00e9tier !<br>Grand moment d&rsquo;\u00e9motion quand No\u00ebl Racine arrive et s&rsquo;amarre \u00e0 c\u00f4t\u00e9 de nous&#8230;&#8230;<br>Et \u00e0 la remise des prix, o\u00f9 le soleil est \u00e0 nouveau de la partie, le spectacle d&rsquo;acrobatie a\u00e9rienne somptueux, No\u00ebl a de nouveau le sourire, on fait des photos sympa des deux \u00e9quipages des JPK 1010 premiers du classement overall, les anglais nous font une ovation d&rsquo;au moins trois minutes et j&rsquo;ai d\u00e9cid\u00e9ment les poignets beaucoup trop petits pour la Rolex &#8230;&#8230;., encore une histoire de r\u00e9glages !<\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00e9cit d&rsquo;une victoire par Pascal LOISON D\u00e9part dimanche 11 ao\u00fbt, devant le Royal Squadron, \u00e0 Cowes ; c&rsquo;est le jour de l&rsquo;anniversaire d&rsquo;Alexis. Je lui demande ce qu&rsquo;il veut comme cadeau d&rsquo;anniversaire, nous convenons qu&rsquo;une Rolex, prix r\u00e9serv\u00e9 au vainqueur toutes classes, ce serait pas mal ! M\u00eame si nous en parlons, l&rsquo;objectif affich\u00e9 ce [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":933,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[9,5],"modele":[141],"class_list":["post-932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-course","tag-fastnet-race","tag-5","modele-jpk-1010"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rolex Fastnet Race 2013 &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/rolex-fastnet-race-2013\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rolex Fastnet Race 2013 &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"R\u00e9cit d&rsquo;une victoire par Pascal LOISON D\u00e9part dimanche 11 ao\u00fbt, devant le Royal Squadron, \u00e0 Cowes ; c&rsquo;est le jour de l&rsquo;anniversaire d&rsquo;Alexis. Je lui demande ce qu&rsquo;il veut comme cadeau d&rsquo;anniversaire, nous convenons qu&rsquo;une Rolex, prix r\u00e9serv\u00e9 au vainqueur toutes classes, ce serait pas mal ! M\u00eame si nous en parlons, l&rsquo;objectif affich\u00e9 ce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/rolex-fastnet-race-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2013-08-30T13:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T14:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"320\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"Rolex Fastnet Race 2013\",\"datePublished\":\"2013-08-30T13:44:00+00:00\",\"dateModified\":\"2026-01-19T14:21:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/\"},\"wordCount\":2917,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2013-nightandday-joan-ahrweiller.jpeg\",\"keywords\":[\"Fastnet Race\",\"JPK 1010\"],\"articleSection\":[\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/\",\"name\":\"Rolex Fastnet Race 2013 &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2013-nightandday-joan-ahrweiller.jpeg\",\"datePublished\":\"2013-08-30T13:44:00+00:00\",\"dateModified\":\"2026-01-19T14:21:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2013-nightandday-joan-ahrweiller.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/2013-nightandday-joan-ahrweiller.jpeg\",\"width\":320,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/rolex-fastnet-race-2013\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/course\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rolex Fastnet Race 2013\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rolex Fastnet Race 2013 &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/rolex-fastnet-race-2013\/","og_locale":"en_GB","og_type":"article","og_title":"Rolex Fastnet Race 2013 &#8212; JPK Composites","og_description":"R\u00e9cit d&rsquo;une victoire par Pascal LOISON D\u00e9part dimanche 11 ao\u00fbt, devant le Royal Squadron, \u00e0 Cowes ; c&rsquo;est le jour de l&rsquo;anniversaire d&rsquo;Alexis. Je lui demande ce qu&rsquo;il veut comme cadeau d&rsquo;anniversaire, nous convenons qu&rsquo;une Rolex, prix r\u00e9serv\u00e9 au vainqueur toutes classes, ce serait pas mal ! M\u00eame si nous en parlons, l&rsquo;objectif affich\u00e9 ce [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/course\/rolex-fastnet-race-2013\/","og_site_name":"JPK Composites","article_published_time":"2013-08-30T13:44:00+00:00","article_modified_time":"2026-01-19T14:21:00+00:00","og_image":[{"width":320,"height":480,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg","type":"image\/jpeg"}],"author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"Rolex Fastnet Race 2013","datePublished":"2013-08-30T13:44:00+00:00","dateModified":"2026-01-19T14:21:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/"},"wordCount":2917,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg","keywords":["Fastnet Race","JPK 1010"],"articleSection":["Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/","url":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/","name":"Rolex Fastnet Race 2013 &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg","datePublished":"2013-08-30T13:44:00+00:00","dateModified":"2026-01-19T14:21:00+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/2013-nightandday-joan-ahrweiller.jpeg","width":320,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/rolex-fastnet-race-2013\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.jpk.fr\/category\/course\/"},{"@type":"ListItem","position":3,"name":"Rolex Fastnet Race 2013"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=932"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/932\/revisions"}],"predecessor-version":[{"id":15996,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/932\/revisions\/15996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/933"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=932"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}