{"id":83,"date":"2021-06-15T16:45:00","date_gmt":"2021-06-15T14:45:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=83"},"modified":"2026-01-19T13:14:55","modified_gmt":"2026-01-19T12:14:55","slug":"fin-de-confinement-les-regates-reprennent","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/fin-de-confinement-les-regates-reprennent\/","title":{"rendered":"Fin de confinement, les r\u00e9gates reprennent !"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Quel bonheur de pouvoir enfin r\u00e9gater de nouveau apr\u00e8s tous ces mois de privation !<\/h3>\n\n\n\n<p>Sur tous les plans d&rsquo;eau, les JPK reprennent leur mission et tentent de ramener le maximum de troph\u00e9es &#8230;<\/p>\n\n\n\n<p>A San Francisco le JPK 1080 \u00ab\u00a0Psycho Tiller \u00a0\u00bb de James Goldberg remporte la 90 mile Spinnaker Cup . A voir le magnifique film avec le passage sous le Golden Gate.<\/p>\n\n\n\n<p>En Manche et sur cette 1ere course du RORC 2021, \u00ab\u00a0Raging Bee\u00a0\u00bb le 1080 de Louis-Marie Dussere remporte la course devant \u00ab\u00a0Ffoggy Dew\u00a0\u00bb le 1030 de Noel Racine ; A priori nos champions n&rsquo;ont pas perdu la main !<\/p>\n\n\n\n<p>En M\u00e9diterran\u00e9e, Eric Merlier s&rsquo;impose sur son nouveau JPK 1030 (1er en r\u00e9el et 2eme compens\u00e9) devant 3 autres JPK 1030 sur la 400 milles Med.<\/p>\n\n\n\n<p>A la Rochelle sur les Terre de Jeanneau la 45\/5 a rassembl\u00e9 plus de 80 bateaux . \u00ab\u00a0L\u00e9on\u00a0\u00bb et \u00ab\u00a0Wasabi\u00a0\u00bb de Sst\u00e9phane Bodin les 2 JPK 1030 ont tent\u00e9 de r\u00e9sister \u00e0 \u00ab\u00a0Sapristi\u00a0\u00bb le 3300 de Alex Ozon qui s&rsquo;impose de 10 mn devant Wasabi apr\u00e8s 48 h de r\u00e9gate au couteau !<\/p>","protected":false},"excerpt":{"rendered":"<p>Quel bonheur de pouvoir enfin r\u00e9gater de nouveau apr\u00e8s tous ces mois de privation ! Sur tous les plans d&rsquo;eau, les JPK reprennent leur mission et tentent de ramener le maximum de troph\u00e9es &#8230; A San Francisco le JPK 1080 \u00ab\u00a0Psycho Tiller \u00a0\u00bb de James Goldberg remporte la 90 mile Spinnaker Cup . A voir [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,8],"tags":[6,7],"modele":[145,143],"class_list":["post-83","post","type-post","status-publish","format-standard","hentry","category-chantier","category-course","tag-6","tag-7","modele-jpk-1030","modele-jpk-1080"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/fin-de-confinement-les-regates-reprennent\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"Quel bonheur de pouvoir enfin r\u00e9gater de nouveau apr\u00e8s tous ces mois de privation ! Sur tous les plans d&rsquo;eau, les JPK reprennent leur mission et tentent de ramener le maximum de troph\u00e9es &#8230; A San Francisco le JPK 1080 \u00ab\u00a0Psycho Tiller \u00a0\u00bb de James Goldberg remporte la 90 mile Spinnaker Cup . A voir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/fin-de-confinement-les-regates-reprennent\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T14:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:14:55+00:00\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"Fin de confinement, les r\u00e9gates reprennent !\",\"datePublished\":\"2021-06-15T14:45:00+00:00\",\"dateModified\":\"2026-01-19T12:14:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"keywords\":[\"JPK 1030\",\"JPK 1080\"],\"articleSection\":[\"Chantier\",\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/\",\"name\":\"Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"datePublished\":\"2021-06-15T14:45:00+00:00\",\"dateModified\":\"2026-01-19T12:14:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/fin-de-confinement-les-regates-reprennent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chantier\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/chantier\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fin de confinement, les r\u00e9gates reprennent !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/fin-de-confinement-les-regates-reprennent\/","og_locale":"en_GB","og_type":"article","og_title":"Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites","og_description":"Quel bonheur de pouvoir enfin r\u00e9gater de nouveau apr\u00e8s tous ces mois de privation ! Sur tous les plans d&rsquo;eau, les JPK reprennent leur mission et tentent de ramener le maximum de troph\u00e9es &#8230; A San Francisco le JPK 1080 \u00ab\u00a0Psycho Tiller \u00a0\u00bb de James Goldberg remporte la 90 mile Spinnaker Cup . A voir [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/course\/fin-de-confinement-les-regates-reprennent\/","og_site_name":"JPK Composites","article_published_time":"2021-06-15T14:45:00+00:00","article_modified_time":"2026-01-19T12:14:55+00:00","author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"Fin de confinement, les r\u00e9gates reprennent !","datePublished":"2021-06-15T14:45:00+00:00","dateModified":"2026-01-19T12:14:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/"},"wordCount":180,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"keywords":["JPK 1030","JPK 1080"],"articleSection":["Chantier","Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/","url":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/","name":"Fin de confinement, les r\u00e9gates reprennent ! &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"datePublished":"2021-06-15T14:45:00+00:00","dateModified":"2026-01-19T12:14:55+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/fin-de-confinement-les-regates-reprennent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Chantier","item":"https:\/\/www.jpk.fr\/category\/chantier\/"},{"@type":"ListItem","position":3,"name":"Fin de confinement, les r\u00e9gates reprennent !"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/83","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"predecessor-version":[{"id":15826,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/83\/revisions\/15826"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=83"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}