{"id":685,"date":"2016-01-29T09:35:00","date_gmt":"2016-01-29T08:35:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=685"},"modified":"2026-01-19T13:14:59","modified_gmt":"2026-01-19T12:14:59","slug":"jpk-present-au-boot-de-dusseldorf","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/chantier\/jpk-present-au-boot-de-dusseldorf\/","title":{"rendered":"JPK pr\u00e9sent au BOOT de Dusseldorf"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Les effets des r\u00e9sulats sur la Sydney\/Hobart et du Fasnet 2015 notamment profitent au rayonnement du chantier \u00e0 l&rsquo;\u00e9tranger &#8230;<\/h2>\n\n\n\n<p>Pr\u00e9sents \u00e0 Dusseldorf avec un JPK 38 nous avons pu mesurer la cote du chantier sur ces nouveaux march\u00e9s de l&rsquo;Europe du Nord.<br>Nous sommes revenus emball\u00e9s de ce salon qui brasse un monde incroyable avec des visiteurs tr\u00e8s connaisseurs.<\/p>\n\n\n\n<p>4 ou 5 fois grand comme le Nautic de Paris, le BOOT rassemble tous les fabricants europ\u00e9ens. Le bilan est excellent en terme de ventes et de qualit\u00e9 de contacts pour le futur. L&rsquo;offre habituelle \u00e9tant assez \u00ab\u00a0classique\u00a0\u00bb nos mod\u00e8les pr\u00e9sentent une alternative entre la performance et le confort.<br>Tout est question de positionnement de curseur car si les amateurs de voiliers \u00e9voluent vers les bateaux plus l\u00e9gers et planants, ils demeurent tr\u00e8s exigeants sur la qualit\u00e9 notamment des d\u00e9tails et de la finition.<br>Bref, la philosophie g\u00e9n\u00e9rale de nos produits a v\u00e9ritablement de l&rsquo;avenir mais il reste \u00e0 encore travailler et am\u00e9liorer ce qui peut l&rsquo;\u00eatre.<br>Avec l&rsquo;arriv\u00e9e prochaine du 45 FC et vu le nombre de prospects plus qu&rsquo;int\u00e9ress\u00e9s par le concept, le challenge est passionnant pour toute l&rsquo;\u00e9quipe JPK.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les effets des r\u00e9sulats sur la Sydney\/Hobart et du Fasnet 2015 notamment profitent au rayonnement du chantier \u00e0 l&rsquo;\u00e9tranger &#8230; Pr\u00e9sents \u00e0 Dusseldorf avec un JPK 38 nous avons pu mesurer la cote du chantier sur ces nouveaux march\u00e9s de l&rsquo;Europe du Nord.Nous sommes revenus emball\u00e9s de ce salon qui brasse un monde incroyable avec [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":686,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10],"tags":[62,42],"modele":[147],"class_list":["post-685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chantier","tag-boot-dusseldorf","tag-38fc","modele-jpk-38-fc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/chantier\/jpk-present-au-boot-de-dusseldorf\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"Les effets des r\u00e9sulats sur la Sydney\/Hobart et du Fasnet 2015 notamment profitent au rayonnement du chantier \u00e0 l&rsquo;\u00e9tranger &#8230; Pr\u00e9sents \u00e0 Dusseldorf avec un JPK 38 nous avons pu mesurer la cote du chantier sur ces nouveaux march\u00e9s de l&rsquo;Europe du Nord.Nous sommes revenus emball\u00e9s de ce salon qui brasse un monde incroyable avec [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/chantier\/jpk-present-au-boot-de-dusseldorf\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-29T08:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"175\" \/>\n\t<meta property=\"og:image:height\" content=\"108\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"JPK pr\u00e9sent au BOOT de Dusseldorf\",\"datePublished\":\"2016-01-29T08:35:00+00:00\",\"dateModified\":\"2026-01-19T12:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/\"},\"wordCount\":217,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Bild175xXXX.jpg\",\"keywords\":[\"BOOT DUSSELDORF\",\"JPK 38 FC\"],\"articleSection\":[\"Chantier\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/\",\"name\":\"JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Bild175xXXX.jpg\",\"datePublished\":\"2016-01-29T08:35:00+00:00\",\"dateModified\":\"2026-01-19T12:14:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Bild175xXXX.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Bild175xXXX.jpg\",\"width\":175,\"height\":108},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/jpk-present-au-boot-de-dusseldorf\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chantier\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/chantier\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JPK pr\u00e9sent au BOOT de Dusseldorf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/chantier\/jpk-present-au-boot-de-dusseldorf\/","og_locale":"en_GB","og_type":"article","og_title":"JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites","og_description":"Les effets des r\u00e9sulats sur la Sydney\/Hobart et du Fasnet 2015 notamment profitent au rayonnement du chantier \u00e0 l&rsquo;\u00e9tranger &#8230; Pr\u00e9sents \u00e0 Dusseldorf avec un JPK 38 nous avons pu mesurer la cote du chantier sur ces nouveaux march\u00e9s de l&rsquo;Europe du Nord.Nous sommes revenus emball\u00e9s de ce salon qui brasse un monde incroyable avec [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/chantier\/jpk-present-au-boot-de-dusseldorf\/","og_site_name":"JPK Composites","article_published_time":"2016-01-29T08:35:00+00:00","article_modified_time":"2026-01-19T12:14:59+00:00","og_image":[{"width":175,"height":108,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg","type":"image\/jpeg"}],"author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"JPK pr\u00e9sent au BOOT de Dusseldorf","datePublished":"2016-01-29T08:35:00+00:00","dateModified":"2026-01-19T12:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/"},"wordCount":217,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg","keywords":["BOOT DUSSELDORF","JPK 38 FC"],"articleSection":["Chantier"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/","url":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/","name":"JPK pr\u00e9sent au BOOT de Dusseldorf &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg","datePublished":"2016-01-29T08:35:00+00:00","dateModified":"2026-01-19T12:14:59+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/Bild175xXXX.jpg","width":175,"height":108},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/chantier\/jpk-present-au-boot-de-dusseldorf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Chantier","item":"https:\/\/www.jpk.fr\/category\/chantier\/"},{"@type":"ListItem","position":3,"name":"JPK pr\u00e9sent au BOOT de Dusseldorf"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/685\/revisions"}],"predecessor-version":[{"id":15931,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/685\/revisions\/15931"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/686"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=685"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}