{"id":3595,"date":"2015-03-20T09:03:13","date_gmt":"2015-03-20T08:03:13","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=3595"},"modified":"2026-01-19T13:15:00","modified_gmt":"2026-01-19T12:15:00","slug":"leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/","title":{"rendered":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias"},"content":{"rendered":"<p class=\"accroche\">En guise de news, un petit Po\u00e8me \u00e9crit par un po\u00e8te qui s&rsquo;ignore, il y a 2 nuits mais qui aurait tout aussi bien \u00eatre \u00e9crit la nuit derni\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<p>Un ciel illumin\u00e9 de mille \u00e9toiles Une mer d\u00e9sesp\u00e9r\u00e9ment lisse<br \/>\nNul souffle de vent dans nos voiles<br \/>\nOn aimerait tant que L\u00e9on glisse<\/p>\n<p>On s&rsquo;\u00e9merveille ou broie du noir<br \/>\nNul doute c&rsquo;est le pot au noir<br \/>\nCelui qui met les nerfs \u00e0 rude \u00e9preuve<br \/>\nNos traits tir\u00e9s en sont la preuve<\/p>\n<p>Un spi qui pend, une grand voile qui bat<br \/>\nUne mer qui secoue notre mat<br \/>\nInutile de chercher \u00e0 r\u00e9gler des voiles qu&rsquo;aucun souffle ne veut gonfler<\/p>\n<p>Une ris\u00e9e, une bouff\u00e9e d&rsquo;air, le bateau d\u00e9marre<br \/>\nEt m\u00eame si c&rsquo;est un faux d\u00e9part,<br \/>\nC&rsquo;est une \u00e9coute \u00e0 la main qu&rsquo;on aime voir<br \/>\nUn instant, le marin reprendre espoir<\/p>\n<p>Si peu de milles parcourus dans la nuit<br \/>\nC&rsquo;est l&rsquo;espoir d&rsquo;une travers\u00e9e record qui fuit<br \/>\nDe Panama aux Galapagos puis aux Marquises<br \/>\nC&rsquo;est le vent qui nous m\u00e8ne \u00e0 sa guise<\/p>\n<p>Michel Q.<br \/>\nL\u00e9on<\/p>\n<p>Depuis ce matin le vent est revenu progressivement et L\u00e9on a repris sa marche en avant.<br \/>\nTout va bien \u00e0 bord.<\/p>\n<p>Biz a tous.<\/p>","protected":false},"excerpt":{"rendered":"<p>En guise de news, un petit Po\u00e8me \u00e9crit par un po\u00e8te qui s&rsquo;ignore, il y a 2 nuits mais qui aurait tout aussi bien \u00eatre \u00e9crit la nuit derni\u00e8re. &nbsp; Un ciel illumin\u00e9 de mille \u00e9toiles Une mer d\u00e9sesp\u00e9r\u00e9ment lisse Nul souffle de vent dans nos voiles On aimerait tant que L\u00e9on glisse On s&rsquo;\u00e9merveille [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[7],"modele":[143],"class_list":["post-3595","post","type-post","status-publish","format-standard","hentry","category-croisiere","tag-7","modele-jpk-1080"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"En guise de news, un petit Po\u00e8me \u00e9crit par un po\u00e8te qui s&rsquo;ignore, il y a 2 nuits mais qui aurait tout aussi bien \u00eatre \u00e9crit la nuit derni\u00e8re. &nbsp; Un ciel illumin\u00e9 de mille \u00e9toiles Une mer d\u00e9sesp\u00e9r\u00e9ment lisse Nul souffle de vent dans nos voiles On aimerait tant que L\u00e9on glisse On s&rsquo;\u00e9merveille [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-20T08:03:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:15:00+00:00\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias\",\"datePublished\":\"2015-03-20T08:03:13+00:00\",\"dateModified\":\"2026-01-19T12:15:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/\"},\"wordCount\":233,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"keywords\":[\"JPK 1080\"],\"articleSection\":[\"Voyage &amp; croisi\u00e8re\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/\",\"name\":\"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"datePublished\":\"2015-03-20T08:03:13+00:00\",\"dateModified\":\"2026-01-19T12:15:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/croisiere\\\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voyage &amp; croisi\u00e8re\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/croisiere\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/","og_locale":"en_GB","og_type":"article","og_title":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites","og_description":"En guise de news, un petit Po\u00e8me \u00e9crit par un po\u00e8te qui s&rsquo;ignore, il y a 2 nuits mais qui aurait tout aussi bien \u00eatre \u00e9crit la nuit derni\u00e8re. &nbsp; Un ciel illumin\u00e9 de mille \u00e9toiles Une mer d\u00e9sesp\u00e9r\u00e9ment lisse Nul souffle de vent dans nos voiles On aimerait tant que L\u00e9on glisse On s&rsquo;\u00e9merveille [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/","og_site_name":"JPK Composites","article_published_time":"2015-03-20T08:03:13+00:00","article_modified_time":"2026-01-19T12:15:00+00:00","author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias","datePublished":"2015-03-20T08:03:13+00:00","dateModified":"2026-01-19T12:15:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/"},"wordCount":233,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"keywords":["JPK 1080"],"articleSection":["Voyage &amp; croisi\u00e8re"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/","url":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/","name":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"datePublished":"2015-03-20T08:03:13+00:00","dateModified":"2026-01-19T12:15:00+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/croisiere\/leon-en-route-vers-le-pacifique-x-par-michel-jean-claude-et-matthias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Voyage &amp; croisi\u00e8re","item":"https:\/\/www.jpk.fr\/category\/croisiere\/"},{"@type":"ListItem","position":3,"name":"L\u00e9on en route vers le Pacifique X par Michel, Jean-Claude et Matthias"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/3595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=3595"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/3595\/revisions"}],"predecessor-version":[{"id":15962,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/3595\/revisions\/15962"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=3595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=3595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=3595"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=3595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}