{"id":343,"date":"2018-09-15T11:38:00","date_gmt":"2018-09-15T09:38:00","guid":{"rendered":"https:\/\/dev.jpk.fr\/?p=343"},"modified":"2026-01-19T13:14:57","modified_gmt":"2026-01-19T12:14:57","slug":"cowes-cherbourg-race-joli-triple-en-irc-3","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/","title":{"rendered":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 !"},"content":{"rendered":"<h2 class=\"wp-block-heading\">En IRC 3 le podium est complet pour les JPK avec en t\u00eate \u00ab\u00a0Shaitan\u00a0\u00bb de Jean-Eudes Renier suivi de pr\u00e8s par \u00ab\u00a0Raging Bee\u00a0\u00bb le 1180 de Loulou Dusserre et \u00ab\u00a0Jangada\u00a0\u00bb le 1010.<\/h2>\n\n\n\n<p>Jean-Eudes Renier nous raconte sa course :<\/p>\n\n\n\n<p>\u00ab\u00a0Apr\u00e8s une bonne sortie du Solent bord \u00e0 bord avec Raging Bee on a tous d\u00e9cid\u00e9 de jouer le courant en allant \u00e0 l&rsquo;ouest au pr\u00e8s dans une brise mollissante qui a pris petit \u00e0 petit de la gauche. Toute la flotte a donc pass\u00e9 la nuit au reaching sous code 0 puis spi max plus ou moins le long de la route directe. Sur \u00ab\u00a0Shaitan\u00a0\u00bb, nous avions d\u00e9cid\u00e9 avec Ruaridh Wright mon jeune \u00e9quipier \u00e9cossais (difficile de tout comprendre \u00e0 bord avec son terrible accent) de rester plus Ouest que la flotte lorsque le vent a commenc\u00e9 \u00e0 mollir jusqu&rsquo;\u00e0 5 nds pour jouer le nouveau vent qu&rsquo;on esp\u00e9rait et ce malgr\u00e8 des fichiers Grib totalement d\u00e9connants !<br>C&rsquo;est finalement ce qui nous a permis de nous \u00e9chapper pour r\u00e9ussir \u00e0 croiser devant la flotte except\u00e9 \u00ab\u00a0Redfish\u00a0\u00bb qui remporte le classement double 4mn devant nous.<br>Au final, 2eme double et 1er IRC 3 devant 2 autres JPK nous sommes contents du r\u00e9sultat ! \u00ab\u00a0<\/p>\n\n\n\n<p>Pour cette derni\u00e8re course de la saison du RORC (except\u00e9 la prochaine Middle Sea Race fin Octobre) il y avait de l&rsquo;enjeu car 3 bateaux se disputent le titre de voilier RORC de l&rsquo;ann\u00e9e toutes cat\u00e9gories confondues. 2\u00e8me intercal\u00e9 le X 41 \u00ab\u00a0British Soldier\u00a0\u00bb devance de peu \u00ab\u00a0Foggy Dew\u00a0\u00bb le JPK 1010 de Noel Racine auteur d&rsquo;une superbe saison \u00e9galement. Noel veut le titre et seule la Middle Sea Race fin Octobre \u00e0 Malte peut lui permettre de ramener le troph\u00e9e \u00e0 la maison.<\/p>\n\n\n\n<p>Prochaine course majeure, la Middle Sea Race avec son parcours exigeant autour de la Sicile et r\u00e9put\u00e9e pour ses conditions parfois dantesques .<br>Au d\u00e9part, cette ann\u00e9e quelques favoris comme \u00ab\u00a0Bogatyr\u00a0\u00bb, le JPK 1080 de nos amis russes qui revient pour d\u00e9fendre son titre overall d\u00e9croch\u00e9 l&rsquo;an dernier dans le vent fort mais aussi le JPK 1180 de Gery trentesaux \u00ab\u00a0Courrier Recommand\u00e9\u00a0\u00bb toujours \u00e9pouvantail au d\u00e9part de toutes ses courses.<br>Pour Gery ce sera le lancement d&rsquo;une campagne 2019 ambitieuse sur toutes les grandes \u00ab\u00a0classiques \u00a0\u00bb dont le Fastnet et la Sydney Hobart d\u00e9ja remport\u00e9es en 2015 avec le 1080 \u00ab\u00a0courrier du l\u00e9on\u00a0\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>En IRC 3 le podium est complet pour les JPK avec en t\u00eate \u00ab\u00a0Shaitan\u00a0\u00bb de Jean-Eudes Renier suivi de pr\u00e8s par \u00ab\u00a0Raging Bee\u00a0\u00bb le 1180 de Loulou Dusserre et \u00ab\u00a0Jangada\u00a0\u00bb le 1010. Jean-Eudes Renier nous raconte sa course : \u00ab\u00a0Apr\u00e8s une bonne sortie du Solent bord \u00e0 bord avec Raging Bee on a tous d\u00e9cid\u00e9 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":344,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8],"tags":[33,5,2],"modele":[141,144],"class_list":["post-343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-course","tag-cowes-cherbourg-race","tag-5","tag-2","modele-jpk-1010","modele-jpk-1180"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"En IRC 3 le podium est complet pour les JPK avec en t\u00eate \u00ab\u00a0Shaitan\u00a0\u00bb de Jean-Eudes Renier suivi de pr\u00e8s par \u00ab\u00a0Raging Bee\u00a0\u00bb le 1180 de Loulou Dusserre et \u00ab\u00a0Jangada\u00a0\u00bb le 1010. Jean-Eudes Renier nous raconte sa course : \u00ab\u00a0Apr\u00e8s une bonne sortie du Solent bord \u00e0 bord avec Raging Bee on a tous d\u00e9cid\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-15T09:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:14:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"JPK Composites\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"JPK Composites\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/\"},\"author\":{\"name\":\"JPK Composites\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\"},\"headline\":\"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 !\",\"datePublished\":\"2018-09-15T09:38:00+00:00\",\"dateModified\":\"2026-01-19T12:14:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RORCDGB-16RT0904L.jpg\",\"keywords\":[\"Cowes Cherbourg Race\",\"JPK 1010\",\"JPK 1180\"],\"articleSection\":[\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/\",\"name\":\"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RORCDGB-16RT0904L.jpg\",\"datePublished\":\"2018-09-15T09:38:00+00:00\",\"dateModified\":\"2026-01-19T12:14:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RORCDGB-16RT0904L.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/RORCDGB-16RT0904L.jpg\",\"width\":1500,\"height\":1001,\"caption\":\"Shaitan De Guingand Bowl RORC race 2016 Photo: Rick Tomlinson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/cowes-cherbourg-race-joli-triple-en-irc-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/course\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/bf695c0f747c688047e68cb3a9358860\",\"name\":\"JPK Composites\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g\",\"caption\":\"JPK Composites\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpk_composites\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/","og_locale":"en_GB","og_type":"article","og_title":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites","og_description":"En IRC 3 le podium est complet pour les JPK avec en t\u00eate \u00ab\u00a0Shaitan\u00a0\u00bb de Jean-Eudes Renier suivi de pr\u00e8s par \u00ab\u00a0Raging Bee\u00a0\u00bb le 1180 de Loulou Dusserre et \u00ab\u00a0Jangada\u00a0\u00bb le 1010. Jean-Eudes Renier nous raconte sa course : \u00ab\u00a0Apr\u00e8s une bonne sortie du Solent bord \u00e0 bord avec Raging Bee on a tous d\u00e9cid\u00e9 [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/","og_site_name":"JPK Composites","article_published_time":"2018-09-15T09:38:00+00:00","article_modified_time":"2026-01-19T12:14:57+00:00","og_image":[{"width":1500,"height":1001,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg","type":"image\/jpeg"}],"author":"JPK Composites","twitter_card":"summary_large_image","twitter_misc":{"Written by":"JPK Composites","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/"},"author":{"name":"JPK Composites","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860"},"headline":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 !","datePublished":"2018-09-15T09:38:00+00:00","dateModified":"2026-01-19T12:14:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/"},"wordCount":401,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg","keywords":["Cowes Cherbourg Race","JPK 1010","JPK 1180"],"articleSection":["Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/","url":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/","name":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 ! &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg","datePublished":"2018-09-15T09:38:00+00:00","dateModified":"2026-01-19T12:14:57+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2021\/11\/RORCDGB-16RT0904L.jpg","width":1500,"height":1001,"caption":"Shaitan De Guingand Bowl RORC race 2016 Photo: Rick Tomlinson"},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/cowes-cherbourg-race-joli-triple-en-irc-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.jpk.fr\/category\/course\/"},{"@type":"ListItem","position":3,"name":"COWES CHERBOURG Race, joli tripl\u00e9 en IRC 3 !"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/bf695c0f747c688047e68cb3a9358860","name":"JPK Composites","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1029a98db5c5e7ced8a03909bc8bfee532d31bca2af4d2e96389ac033b3138d4?s=96&d=mm&r=g","caption":"JPK Composites"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpk_composites\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"predecessor-version":[{"id":15873,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/343\/revisions\/15873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/344"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=343"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}