{"id":12397,"date":"2025-05-27T12:56:55","date_gmt":"2025-05-27T10:56:55","guid":{"rendered":"https:\/\/www.jpk.fr\/?p=12397"},"modified":"2026-01-19T13:14:47","modified_gmt":"2026-01-19T12:14:47","slug":"retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/","title":{"rendered":"The Nomad 40 and JPK 39 FC at the Venice Boat Show"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12397\" class=\"elementor elementor-12397\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3513f e-flex e-con-boxed e-con e-parent\" data-id=\"6b3513f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d3beb3 elementor-widget elementor-widget-text-editor\" data-id=\"1d3beb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The Venice Boat Show, a not-to-be-missed international event, returns from 29 May to 2 June 2025 in the prestigious setting of the Venice Arsenale. With 55,000 m\u00b2 of water and nearly 300 boats, 270 exhibitors will be showcasing the latest nautical innovations. Organised by Vela Spa in collaboration with the Italian Navy and supported by the City of Venice, the event offers five intense days of presentations, themed conferences, sea trials and sports regattas. It's the ideal opportunity to discover the trends of 2025, talk to designers and try out the boats directly on the quayside or underway.<\/p><h2>Our boats on display<\/h2><p>JPK Composites is one of the exhibitors at this year's show, with the brand new JPK Nomad 40, the shipyard's first motorboat, and the now unmissable JPK 39 FC. They will be on display at the following locations:<\/p><p>\ud83d\udea4 JPK Nomad 40 \u2013 Motor boats (P1 \u2013 NORD, Pontili P1 \/ P2 \/ P3)<\/p><p>\u26f5 JPK 39 FC \u2013 Sailboats (P3 \u2013 SUD, Pontili P1 \/ P2 \/ P3)<\/p><h2>Practical information<\/h2><p>Dates: 29 May - 2 June 2025<br \/>Place: Arsenale di Venezia, Giardini della Biennale<br \/>Opening hours: 10am - 6pm (last day 10am - 5pm)<br \/>Tickets: online on the official Venice Boat Show website<br \/>Acc\u00e8s : vaporetto - ligne 4.1, 4.2 ; parking Tronchetto + shuttle<\/p><p>More information and planning on <a href=\"https:\/\/salonenautico.venezia.it\/en\/\">the official website<\/a>, link below:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fc5270 elementor-widget elementor-widget-button\" data-id=\"4fc5270\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/salonenautico.venezia.it\/en\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"material-icons md-arrow_outward\" data-md-icon=\"arrow_outward\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Venice Boat Show official website<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Le Venice Boat Show, rendez-vous international incontournable, revient du 29 mai au 2 juin 2025 dans le cadre prestigieux de l\u2019Arsenale de Venise. Sur 55 000 m\u00b2 de plan d\u2019eau et pr\u00e8s de 300 bateaux, 270 exposants pr\u00e9senteront les derni\u00e8res innovations nautiques. Organis\u00e9 par Vela Spa en collaboration avec la Marine italienne et soutenu par [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12398,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,31],"tags":[11,106],"modele":[148,150],"class_list":["post-12397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chantier","category-croisiere","tag-jpk-39-fc","tag-jpk-nomad-40","modele-jpk-39-fc","modele-jpk-nomad-40"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"Le Venice Boat Show, rendez-vous international incontournable, revient du 29 mai au 2 juin 2025 dans le cadre prestigieux de l\u2019Arsenale de Venise. Sur 55 000 m\u00b2 de plan d\u2019eau et pr\u00e8s de 300 bateaux, 270 exposants pr\u00e9senteront les derni\u00e8res innovations nautiques. Organis\u00e9 par Vela Spa en collaboration avec la Marine italienne et soutenu par [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-27T10:56:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:14:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"C\u00f4me de Pr\u00e9ville\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"C\u00f4me de Pr\u00e9ville\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/\"},\"author\":{\"name\":\"C\u00f4me de Pr\u00e9ville\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/0ab05414e33b33d72c5db97fd3062831\"},\"headline\":\"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise\",\"datePublished\":\"2025-05-27T10:56:55+00:00\",\"dateModified\":\"2026-01-19T12:14:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/\"},\"wordCount\":225,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/snv-24.jpg\",\"keywords\":[\"JPK 39 FC\",\"JPK Nomad 40\"],\"articleSection\":[\"Chantier\",\"Voyage &amp; croisi\u00e8re\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/\",\"name\":\"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/snv-24.jpg\",\"datePublished\":\"2025-05-27T10:56:55+00:00\",\"dateModified\":\"2026-01-19T12:14:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/snv-24.jpg\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/snv-24.jpg\",\"width\":2048,\"height\":1493},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/chantier\\\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chantier\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/chantier\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/0ab05414e33b33d72c5db97fd3062831\",\"name\":\"C\u00f4me de Pr\u00e9ville\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g\",\"caption\":\"C\u00f4me de Pr\u00e9ville\"},\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/comedepreville\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/","og_locale":"en_GB","og_type":"article","og_title":"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites","og_description":"Le Venice Boat Show, rendez-vous international incontournable, revient du 29 mai au 2 juin 2025 dans le cadre prestigieux de l\u2019Arsenale de Venise. Sur 55 000 m\u00b2 de plan d\u2019eau et pr\u00e8s de 300 bateaux, 270 exposants pr\u00e9senteront les derni\u00e8res innovations nautiques. Organis\u00e9 par Vela Spa en collaboration avec la Marine italienne et soutenu par [&hellip;]","og_url":"https:\/\/www.jpk.fr\/en\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/","og_site_name":"JPK Composites","article_published_time":"2025-05-27T10:56:55+00:00","article_modified_time":"2026-01-19T12:14:47+00:00","og_image":[{"width":2048,"height":1493,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg","type":"image\/jpeg"}],"author":"C\u00f4me de Pr\u00e9ville","twitter_card":"summary_large_image","twitter_misc":{"Written by":"C\u00f4me de Pr\u00e9ville","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/"},"author":{"name":"C\u00f4me de Pr\u00e9ville","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/0ab05414e33b33d72c5db97fd3062831"},"headline":"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise","datePublished":"2025-05-27T10:56:55+00:00","dateModified":"2026-01-19T12:14:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/"},"wordCount":225,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg","keywords":["JPK 39 FC","JPK Nomad 40"],"articleSection":["Chantier","Voyage &amp; croisi\u00e8re"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/","url":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/","name":"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg","datePublished":"2025-05-27T10:56:55+00:00","dateModified":"2026-01-19T12:14:47+00:00","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2025\/05\/snv-24.jpg","width":2048,"height":1493},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/chantier\/retrouvez-le-nomad-40-et-le-jpk-39-fc-au-salon-nautique-de-venise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Chantier","item":"https:\/\/www.jpk.fr\/category\/chantier\/"},{"@type":"ListItem","position":3,"name":"Retrouvez le Nomad 40 et le JPK 39 FC au Salon Nautique de Venise"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/0ab05414e33b33d72c5db97fd3062831","name":"C\u00f4me de Pr\u00e9ville","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/422f369cd3cc3ebfcd421172d35842c2811fae14ebdab6ca9ede7f28c9f1c130?s=96&d=mm&r=g","caption":"C\u00f4me de Pr\u00e9ville"},"url":"https:\/\/www.jpk.fr\/en\/author\/comedepreville\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/12397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=12397"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/12397\/revisions"}],"predecessor-version":[{"id":15661,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/12397\/revisions\/15661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/12398"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=12397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=12397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=12397"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=12397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}