{"id":10014,"date":"2024-05-27T20:09:43","date_gmt":"2024-05-27T18:09:43","guid":{"rendered":"https:\/\/www.jpk.fr\/?p=10014"},"modified":"2026-01-19T13:14:48","modified_gmt":"2026-01-19T12:14:48","slug":"le-jpk-1050-verra-le-jour-fin-2024","status":"publish","type":"post","link":"https:\/\/www.jpk.fr\/en\/course\/le-jpk-1050-verra-le-jour-fin-2024\/","title":{"rendered":"Le JPK 1050 verra le jour fin 2024"},"content":{"rendered":"<p>The yard's new IRC boat was initially planned to be around 10.80\/10.85 metres in length, with a hull fairly close to the JPK 1030.<\/p>\n<p>In order to stay within a rating range that allows access to the interesting events in the solo and double-handed programme, the size had to be reduced to allow the design and concept to be radicalised.<\/p>\n<p>Jacques Valer avait d\u00e8s 2018 dessin\u00e9 le JPK 1030 dans une version \u00ab\u00a0scow\u00a0\u00bb, pour finalement assagir le dessin afin de conserver une polyvalence que nous avions peur de perdre. D\u00e9sormais, il est clair que le concept fonctionne avec l&rsquo;exemple du MN 35 qui arrive tr\u00e8s souvent \u00e0 sauver son rating, pourtant tr\u00e8s haut. Le concept,\u00a0un bateau tr\u00e8s puissant avec des sections avant pleines (type scow) et un rapport voilure\/d\u00e9placement inhabituel pour un bateau IRC est au rendez-vous : le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances int\u00e9ressantes au pr\u00e8s gr\u00e2ce \u00e0 sa puissance qui permet d&rsquo;exploiter une surface de voile tr\u00e8s importante, m\u00eame dans la brise.<\/p>\n<p>Apr\u00e8s plus de 10 mois de travail sur la planche \u00e0 dessin, le mod\u00e8le de coque est d\u00e9sormais en cours de production pour la sortie d&rsquo;un 1er mod\u00e8le \u00ab\u00a0chantier\u00a0\u00bb en fin d&rsquo;ann\u00e9e 2024 et une premi\u00e8re s\u00e9rie de bateaux disponibles d\u00e8s le printemps 2025.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le nouveau bateau IRC du chantier \u00e9tait initialement pr\u00e9vu autour de 10.80\/10.85 m\u00e8tres de longueur, et avec une car\u00e8ne assez proche du JPK 1030. Afin de rester dans une fourchette de rating permettant l&rsquo;acc\u00e8s aux \u00e9preuves int\u00e9ressantes du programme solo et double, la taille a d\u00fb \u00eatre revue \u00e0 la baisse pour permettre de radicaliser [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9991,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10,8],"tags":[],"modele":[],"class_list":["post-10014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chantier","category-course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites<\/title>\n<meta name=\"description\" content=\"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jpk.fr\/en\/course\/le-jpk-1050-verra-le-jour-fin-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites\" \/>\n<meta property=\"og:description\" content=\"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jpk.fr\/en\/course\/le-jpk-1050-verra-le-jour-fin-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"JPK Composites\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-27T18:09:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jean-Pierre Kelbert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jean-Pierre Kelbert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/\"},\"author\":{\"name\":\"Jean-Pierre Kelbert\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/9135360ca6e56dfc7e3ff11c5e2952c9\"},\"headline\":\"Le JPK 1050 verra le jour fin 2024\",\"datePublished\":\"2024-05-27T18:09:43+00:00\",\"dateModified\":\"2026-01-19T12:14:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/\"},\"wordCount\":246,\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image002.png\",\"articleSection\":[\"Chantier\",\"Course\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/\",\"name\":\"Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image002.png\",\"datePublished\":\"2024-05-27T18:09:43+00:00\",\"dateModified\":\"2026-01-19T12:14:48+00:00\",\"description\":\"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image002.png\",\"contentUrl\":\"https:\\\/\\\/www.jpk.fr\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/image002.png\",\"width\":1512,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/course\\\/le-jpk-1050-verra-le-jour-fin-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Course\",\"item\":\"https:\\\/\\\/www.jpk.fr\\\/category\\\/course\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le JPK 1050 verra le jour fin 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"name\":\"JPK Composites\",\"description\":\"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jpk.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#organization\",\"name\":\"JPK Composites\",\"url\":\"https:\\\/\\\/www.jpk.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"JPK Composites\"},\"image\":{\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jpk.fr\\\/#\\\/schema\\\/person\\\/9135360ca6e56dfc7e3ff11c5e2952c9\",\"name\":\"Jean-Pierre Kelbert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g\",\"caption\":\"Jean-Pierre Kelbert\"},\"sameAs\":[\"https:\\\/\\\/www.jpk.fr\"],\"url\":\"https:\\\/\\\/www.jpk.fr\\\/en\\\/author\\\/jpkelbert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites","description":"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jpk.fr\/en\/course\/le-jpk-1050-verra-le-jour-fin-2024\/","og_locale":"en_GB","og_type":"article","og_title":"Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites","og_description":"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.","og_url":"https:\/\/www.jpk.fr\/en\/course\/le-jpk-1050-verra-le-jour-fin-2024\/","og_site_name":"JPK Composites","article_published_time":"2024-05-27T18:09:43+00:00","article_modified_time":"2026-01-19T12:14:48+00:00","og_image":[{"width":1512,"height":688,"url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png","type":"image\/png"}],"author":"Jean-Pierre Kelbert","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Jean-Pierre Kelbert","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#article","isPartOf":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/"},"author":{"name":"Jean-Pierre Kelbert","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/9135360ca6e56dfc7e3ff11c5e2952c9"},"headline":"Le JPK 1050 verra le jour fin 2024","datePublished":"2024-05-27T18:09:43+00:00","dateModified":"2026-01-19T12:14:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/"},"wordCount":246,"publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png","articleSection":["Chantier","Course"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/","url":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/","name":"Le JPK 1050 verra le jour fin 2024 &#8212; JPK Composites","isPartOf":{"@id":"https:\/\/www.jpk.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#primaryimage"},"image":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png","datePublished":"2024-05-27T18:09:43+00:00","dateModified":"2026-01-19T12:14:48+00:00","description":"Le JPK 1050 sera un bateau tr\u00e8s planant, ultra performant au reaching et globalement au portant mais conservant des performances au pr\u00e8s.","breadcrumb":{"@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#primaryimage","url":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png","contentUrl":"https:\/\/www.jpk.fr\/wp-content\/uploads\/2024\/05\/image002.png","width":1512,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/www.jpk.fr\/course\/le-jpk-1050-verra-le-jour-fin-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.jpk.fr\/"},{"@type":"ListItem","position":2,"name":"Course","item":"https:\/\/www.jpk.fr\/category\/course\/"},{"@type":"ListItem","position":3,"name":"Le JPK 1050 verra le jour fin 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.jpk.fr\/#website","url":"https:\/\/www.jpk.fr\/","name":"JPK Composites","description":"JPK Composites d\u00e9veloppe avec une \u00e9quipe passionn\u00e9e des bateaux rapides, marins, et esth\u00e9tiques.","publisher":{"@id":"https:\/\/www.jpk.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jpk.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.jpk.fr\/#organization","name":"JPK Composites","url":"https:\/\/www.jpk.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"JPK Composites"},"image":{"@id":"https:\/\/www.jpk.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.jpk.fr\/#\/schema\/person\/9135360ca6e56dfc7e3ff11c5e2952c9","name":"Jean-Pierre Kelbert","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ae69dc6786666602e1aab054f646f1075697c25d8b06f175fe645ac320d01b5?s=96&d=mm&r=g","caption":"Jean-Pierre Kelbert"},"sameAs":["https:\/\/www.jpk.fr"],"url":"https:\/\/www.jpk.fr\/en\/author\/jpkelbert\/"}]}},"_links":{"self":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/10014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/comments?post=10014"}],"version-history":[{"count":1,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/10014\/revisions"}],"predecessor-version":[{"id":15674,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/posts\/10014\/revisions\/15674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media\/9991"}],"wp:attachment":[{"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/media?parent=10014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/categories?post=10014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/tags?post=10014"},{"taxonomy":"modele","embeddable":true,"href":"https:\/\/www.jpk.fr\/en\/wp-json\/wp\/v2\/modele?post=10014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}